{"id":481,"date":"2017-10-01T12:00:33","date_gmt":"2017-10-01T10:00:33","guid":{"rendered":"http:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/?p=481"},"modified":"2017-10-19T14:05:09","modified_gmt":"2017-10-19T12:05:09","slug":"no-hablar-de-cataluna","status":"publish","type":"post","link":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/2017\/10\/01\/no-hablar-de-cataluna\/","title":{"rendered":"No hablar de Catalu\u00f1a"},"content":{"rendered":"<p>Por supuesto, todo esto se ve\u00eda venir. Tras varias generaciones educadas bajo los preceptos nacionalistas, aquello del \u00abEl r\u00edo Ebro nace en tierras extra\u00f1as y desemboca en el Mediterr\u00e1neo por Catalu\u00f1a\u00bb ha acabado calando hondo entre los catalanes. El discurso victimista del pa\u00eds invadido desde la guerra de Sucesi\u00f3n, la pol\u00edtica de ganar para la causa a los emigrantes de segunda generaci\u00f3n \u2013cuando se convencieron de que era mucho mejor que llamarles \u2018charnegos\u2019; v\u00e9ase si no qu\u00e9 \u00e9xito con Rufi\u00e1n y sus clones\u2013 o la potenciaci\u00f3n del \u2018hecho diferencial\u2019 llevan cuatro d\u00e9cadas incubando un sentimiento que en alg\u00fan momento ten\u00eda que explotar.<!--more--><\/p>\n<p>En 2004 hice en la Universitat de Girona \u2013entonces ya no se pod\u00eda decir oficialmente \u2018Universidad de Gerona\u2019, ni siquiera en castellano\u2013 un curso de catal\u00e1n en su escuela de idiomas veraniega. Cosas del requisito ling\u00fc\u00edstico, que ya separaba de facto Catalu\u00f1a de Espa\u00f1a, al menos en lo laboral. La verdad es que la estancia result\u00f3 maravillosa \u2013como en todas las visitas que he realizado a Catalu\u00f1a\u2013; la gente era encantadora, no ten\u00edan el menor problema con el biling\u00fcismo y pas\u00e9 seis semanas fabulosas, disfrutando de un lugar y una cultura que, si no era la m\u00eda, se parec\u00eda much\u00edsimo.<\/p>\n<p>Hasta que, al concluir el curso, en un acto con todos los asistentes a las clases de los dem\u00e1s idiomas, la universidad quiso agradecer a los estudiantes de catal\u00e1n su presencia con una ovaci\u00f3n, repartida por pa\u00edses. Grandes aplausos para los alemanes, los franceses, los italianos, los marroqu\u00edes y los japoneses. Cuando nos toc\u00f3 salir a los espa\u00f1oles, el chaparr\u00f3n fue antol\u00f3gico. Silbidos, abucheos y hasta insultos gruesos para las cinco personas que salimos detr\u00e1s de la palabra \u2018Espa\u00f1a\u2019, como si no estuvi\u00e9ramos en nuestro propio pa\u00eds. Y muchas de las caras que nos miraban con resentimiento eran las mismas con las que hab\u00edamos convivido sin el menor problema hasta entonces.<\/p>\n<p>Pero se aprecia la misma violencia injustificada en los que ahora se dedican a jalear a las fuerzas de orden; \u00bfqu\u00e9 es eso de \u00ab\u00a1A por ellos!\u00bb? \u00bfA por qui\u00e9n? Habr\u00eda que empezar por hacer un esfuerzo por entendernos. Para los espa\u00f1oles, la secesi\u00f3n se interpreta como una p\u00e9rdida traum\u00e1tica, como amputarse una pierna o un brazo. Los independentistas, en cambio, lo ven como un divorcio que pondr\u00eda fin a un matrimonio forzado.<\/p>\n<p>El sentimiento independentista es real, y no es nada nuevo. Desde el otro lado de la pen\u00ednsula nos consolamos pensando que son cuatro gatos, una minor\u00eda muy vociferante, y nos refugiamos detr\u00e1s de leyes, jueces y fuerzas del orden para pensar que todo va bien, que nunca cambiar\u00e1 nada. El plan es no hablar de Catalu\u00f1a. Y tal vez ese sea tambi\u00e9n el error: no hablar de Catalu\u00f1a. Al menos, no del problema real que nos separa. Lo hemos ignorado tanto tiempo, que quiz\u00e1s ahora ya sea demasiado tarde.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Por supuesto, todo esto se ve\u00eda venir. Tras varias generaciones educadas bajo los preceptos nacionalistas, aquello del \u00abEl r\u00edo Ebro nace en tierras extra\u00f1as y desemboca en el Mediterr\u00e1neo por Catalu\u00f1a\u00bb ha acabado calando hondo entre los catalanes. El discurso victimista del pa\u00eds invadido desde la guerra de Sucesi\u00f3n, la pol\u00edtica de ganar para la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[77,54],"class_list":["post-481","post","type-post","status-publish","format-standard","hentry","category-opinion-dm","tag-cataluna","tag-politica"],"_links":{"self":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/comments?post=481"}],"version-history":[{"count":1,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts\/481\/revisions"}],"predecessor-version":[{"id":482,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts\/481\/revisions\/482"}],"wp:attachment":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/media?parent=481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/categories?post=481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/tags?post=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}