{"id":160,"date":"2015-05-03T14:56:04","date_gmt":"2015-05-03T12:56:04","guid":{"rendered":"http:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/?p=160"},"modified":"2015-05-03T14:56:04","modified_gmt":"2015-05-03T12:56:04","slug":"procrastinar","status":"publish","type":"post","link":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/2015\/05\/03\/procrastinar\/","title":{"rendered":"Procrastinar"},"content":{"rendered":"<p>Por muy desconocido que nos resulte el verbo \u2013y m\u00e1s bien feo, que todo hay que decirlo\u2013, lo de \u2018procrastinar\u2019 es una man\u00eda de lo m\u00e1s extendida; algo de lo que, en mayor o menor medida, todos nos acabamos arrepintiendo, pero en lo que caemos casi sin remisi\u00f3n.<\/p>\n<p>Se trata, claro, de un latinajo, un cultismo de esos que tanto adornan, pero en el fondo el asunto de la procrastinaci\u00f3n es m\u00e1s bien un deporte nacional, consistente en dejar para ma\u00f1ana lo que podr\u00edas hacer hoy. Algo que, sin esforzarnos demasiado, podemos observar constantemente; en el alumno que ya estudiar\u00e1 en junio, en el padre que ya ba\u00f1ar\u00e1 a los ni\u00f1os cuando termine el partido o incluso en el articulista que deja su columna para \u00faltima hora, esperando que la inspiraci\u00f3n le encuentre distra\u00eddo.<\/p>\n<p>Aunque tambi\u00e9n hay dilaciones colectivas, que son m\u00e1s bien una manera de comprobar c\u00f3mo esta costumbre est\u00e1 mucho m\u00e1s arraigada de lo que pudiera parecer, ahora que somos tan competitivos, tan europeos y tan neoliberales todos. Y no hace falta ir a los Campos de Sport para comprobar c\u00f3mo el noventa por ciento del p\u00fablico llega apurando el reloj \u2013incluso, los que antes tienen que pasar por taquilla, y se pierden los primeros minutos refunfu\u00f1ando en la cola\u2013; qu\u00e9 va. La prueba m\u00e1s palpable la hemos tenido esta semana en las oficinas bancarias, atestadas desde primera hora por todos los clientes que intent\u00e1bamos evitar que nos hicieran el corralito de Rajoy por un qu\u00edtame all\u00e1 esc\u00e1ner.<\/p>\n<p>Para quien no lo supiera, el viernes deb\u00eda de parecer que en los bancos y cajas regalaban dinero, porque las colas sal\u00edan hasta la calle, y como hay una oficina en cada esquina, algunas llegaban a juntarse y hasta confundirse, formando un enjambre de ciudadanos cabreados.<\/p>\n<p>Y es que los \u00faltimos rezagados \u00e9ramos, en realidad, el grueso del pelot\u00f3n. Un avispero de tardones, que por no perder diez minutos en las semanas anteriores terminar\u00edamos por malgastar una ma\u00f1ana, y arreados adem\u00e1s por terribles amenazas \u2013ojo, que los bancos no se ponen chulos: ellos si dicen que te bloquean la cuenta, lo hacen sin pesta\u00f1ear\u2013. Todo fuera por evitar que los tristes trabajadores espa\u00f1oles blanque\u00e1semos dinero, como si fu\u00e9ramos pol\u00edticos o financieros\u2026 El caso es que, el \u2018tarde, mal y nunca\u2019 volvi\u00f3 a ser santo y se\u00f1a de un alt\u00edsimo porcentaje de la poblaci\u00f3n.<\/p>\n<p>Pero no es que seamos mala gente, ni nada de eso \u2013ni vagos redomados, que dec\u00edan las madres de antes\u2013, qu\u00e9 va. Seg\u00fan los expertos, es un trastorno psicol\u00f3gico. Lo de que sea muy grave o no todav\u00eda no lo s\u00e9, porque a\u00fan no he le\u00eddo esas p\u00e1ginas, igual ma\u00f1ana\u2026 O pasado. O, como dice Mari\u00e1n, \u00abme lo apunto en tareas pendientes\u00bb.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Por muy desconocido que nos resulte el verbo \u2013y m\u00e1s bien feo, que todo hay que decirlo\u2013, lo de \u2018procrastinar\u2019 es una man\u00eda de lo m\u00e1s extendida; algo de lo que, en mayor o menor medida, todos nos acabamos arrepintiendo, pero en lo que caemos casi sin remisi\u00f3n. Se trata, claro, de un latinajo, un [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-160","post","type-post","status-publish","format-standard","hentry","category-opinion-dm"],"_links":{"self":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts\/160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/comments?post=160"}],"version-history":[{"count":0,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/posts\/160\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/media?parent=160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/categories?post=160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.eldiariomontanes.es\/llamazaresensutinta\/wp-json\/wp\/v2\/tags?post=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}